                <script>                   
                    var posts_already_showed = 9,
                        categories = "64"            
                    function get_works() {
                                                    gt3_get_isotope_posts("port", 9, posts_already_showed, "port_module_isotope", "#list", categories, '0', 'id', '740', '500');
                                                
                        posts_already_showed = posts_already_showed + 9;
                    }
                    jQuery(document).ready(function () {
                        jQuery('.fs_port_loadmore').on('click', function(){
                            get_works();
                        });
                    });            
                </script>    
                
                {"id":613,"date":"2022-10-20T09:15:35","date_gmt":"2022-10-20T14:15:35","guid":{"rendered":"https:\/\/www.ccabogados.com\/?page_id=613\/"},"modified":"2024-06-11T10:32:11","modified_gmt":"2024-06-11T15:32:11","slug":"visas","status":"publish","type":"page","link":"https:\/\/www.ccabogados.com\/es\/visas\/","title":{"rendered":"Visas"},"content":{"rendered":"<div class=\"bg_start_module fw_block stretch  left-center-background \" data-option=\"stretch\" style= \"background: #f8f8f8 url('https:\/\/www.ccabogados.com\/wp-content\/uploads\/2024\/06\/Visas.webp') repeat 0 0; padding-top:0px; margin-bottom:35px;\"><div class='row'><div style='padding-bottom:50px; padding-top:50px; padding-left:15px; padding-right:15px' class='col-xs-12 first-module module_number_1 module_cont  center_title module_title'><div class='module_wrapper'><div class='bg_title centered' style='text-align:center;'><h3 style='' class='headInModule'><h1 style=\"color:#ffffff;\">Visas<\/h1><\/h3><span class='subtitle'><p style=\"color:#ffffff;\">CANDANEDO CORREA ofrece representaci\u00f3n legal y asesor\u00eda para la obtenci\u00f3n de las siguientes visas:<\/p><\/span><div class='heading_title_divider' style='border-color:#e4e6e8;'><\/div><\/div><\/div><\/div><\/div><\/div><!-- module_bg_end --><div class='row'><div style='padding-bottom:35px; padding-top:40px; padding-left:15px; padding-right:15px' class='col-xs-12  module_number_2 module_cont portafolio center_title module_portfolio'><div class=\"portfolio_block image-grid columns3\" id=\"list\">\n\t\t\t\t<div data-category=\"visas \" class=\"visas  element portfolio_item\">\n\t\t\t\t\t<div class=\"portfolio_item_block\">\n\t\t\t\t\t\t<div class=\"portfolio_item_wrapper\">\n\t\t\t\t\t\t\t<div class=\"img_block wrapped_img\">\n\t\t\t\t\t\t\t\t<a target=\"_self\" href=\"https:\/\/www.ccabogados.com\/es\/info\/visa-de-inversionistas-calificados\/\" class=\"featured_ico_link\"><img decoding=\"async\" src=\"https:\/\/www.ccabogados.com\/wp-content\/uploads\/2024\/09\/qualified-investors-visa-66e21ab46b3ca-740x500.webp\" alt=\"Invertir en Bienes Ra\u00edces\" \/><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"bottom_box\">\n\t\t\t\t\t\t\t\t<div class=\"bc_content\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"bc_title\"><a target=\"_self\" href=\"https:\/\/www.ccabogados.com\/es\/info\/visa-de-inversionistas-calificados\/\">Visa de Inversionistas Calificados<\/a><\/h2>\n\t\t\t\t\t\t\t\t\t<div class=\"featured_items_meta\"><a href=\"https:\/\/www.ccabogados.com\/es\/portcat\/visas\/\">Visas<\/a>\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n                                <div class=\"excerpt\">Esta visa otorga Residencia Permanente a los solicitantes que inviertan en bienes ra\u00edces en Panam\u00e1 por un m\u00ednimo de US$500,000. En este momento y hasta octubre de 2024, la inversi\u00f3n m\u00ednima es de US$300,000.<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-category=\"visas \" class=\"visas  element portfolio_item\">\n\t\t\t\t\t<div class=\"portfolio_item_block\">\n\t\t\t\t\t\t<div class=\"portfolio_item_wrapper\">\n\t\t\t\t\t\t\t<div class=\"img_block wrapped_img\">\n\t\t\t\t\t\t\t\t<a target=\"_self\" href=\"https:\/\/www.ccabogados.com\/es\/info\/visa-para-inversionistas-agrarios\/\" class=\"featured_ico_link\"><img decoding=\"async\" src=\"https:\/\/www.ccabogados.com\/wp-content\/uploads\/2023\/01\/Visa-para-Inversionistas-Agrarios-740x500.webp\" alt=\"Visa para Inversionistas Agrarios\" \/><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"bottom_box\">\n\t\t\t\t\t\t\t\t<div class=\"bc_content\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"bc_title\"><a target=\"_self\" href=\"https:\/\/www.ccabogados.com\/es\/info\/visa-para-inversionistas-agrarios\/\">Visa para Inversionistas Agrarios<\/a><\/h2>\n\t\t\t\t\t\t\t\t\t<div class=\"featured_items_meta\"><a href=\"https:\/\/www.ccabogados.com\/es\/portcat\/visas\/\">Visas<\/a>\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n                                <div class=\"excerpt\">En relaci\u00f3n con los tr\u00e1mites migratorios para aplicar a una residencia en nuestro pa\u00eds a trav\u00e9s de una Visa de Inversionista Agraria, tenemos a bien detallarles los requisitos, gastos, honorarios y tiempo de tramitaci\u00f3n para realizar los mismos.<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-category=\"visas \" class=\"visas  element portfolio_item\">\n\t\t\t\t\t<div class=\"portfolio_item_block\">\n\t\t\t\t\t\t<div class=\"portfolio_item_wrapper\">\n\t\t\t\t\t\t\t<div class=\"img_block wrapped_img\">\n\t\t\t\t\t\t\t\t<a target=\"_self\" href=\"https:\/\/www.ccabogados.com\/es\/info\/visas-de-permiso-de-trabajo\/\" class=\"featured_ico_link\"><img decoding=\"async\" src=\"https:\/\/www.ccabogados.com\/wp-content\/uploads\/2022\/12\/Visas-de-permiso-de-trabajo-740x500.webp\" alt=\"Visas de permiso de trabajo\" \/><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"bottom_box\">\n\t\t\t\t\t\t\t\t<div class=\"bc_content\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"bc_title\"><a target=\"_self\" href=\"https:\/\/www.ccabogados.com\/es\/info\/visas-de-permiso-de-trabajo\/\">Visas de permiso de trabajo<\/a><\/h2>\n\t\t\t\t\t\t\t\t\t<div class=\"featured_items_meta\"><a href=\"https:\/\/www.ccabogados.com\/es\/portcat\/visas\/\">Visas<\/a>\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n                                <div class=\"excerpt\">En relaci\u00f3n con su solicitud de los tr\u00e1mites migratorios y de permiso de trabajo, usted podr\u00eda aplicar a un permiso temporal de residencia como trabajador contratado por una empresa bajo el acuerdo de Marrakech. <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-category=\"visas \" class=\"visas  element portfolio_item\">\n\t\t\t\t\t<div class=\"portfolio_item_block\">\n\t\t\t\t\t\t<div class=\"portfolio_item_wrapper\">\n\t\t\t\t\t\t\t<div class=\"img_block wrapped_img\">\n\t\t\t\t\t\t\t\t<a target=\"_self\" href=\"https:\/\/www.ccabogados.com\/es\/info\/visa-de-paises-amigos\/\" class=\"featured_ico_link\"><img decoding=\"async\" src=\"https:\/\/www.ccabogados.com\/wp-content\/uploads\/2022\/11\/Visa-de-Paises-Amigos-740x500.webp\" alt=\"Visa de Pa\u00edses Amigos\" \/><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"bottom_box\">\n\t\t\t\t\t\t\t\t<div class=\"bc_content\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"bc_title\"><a target=\"_self\" href=\"https:\/\/www.ccabogados.com\/es\/info\/visa-de-paises-amigos\/\">Visa de Pa\u00edses Amigos<\/a><\/h2>\n\t\t\t\t\t\t\t\t\t<div class=\"featured_items_meta\"><a href=\"https:\/\/www.ccabogados.com\/es\/portcat\/visas\/\">Visas<\/a>\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n                                <div class=\"excerpt\">El tr\u00e1mite comienza en las oficinas de Migraci\u00f3n. Al presentar los requisitos completos junto a la solicitud de visa, Migraci\u00f3n emitir\u00e1 un carn\u00e9 provisional de visa en tr\u00e1mite.<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-category=\"visas \" class=\"visas  element portfolio_item\">\n\t\t\t\t\t<div class=\"portfolio_item_block\">\n\t\t\t\t\t\t<div class=\"portfolio_item_wrapper\">\n\t\t\t\t\t\t\t<div class=\"img_block wrapped_img\">\n\t\t\t\t\t\t\t\t<a target=\"_self\" href=\"https:\/\/www.ccabogados.com\/es\/info\/visa-de-jubilado\/\" class=\"featured_ico_link\"><img decoding=\"async\" src=\"https:\/\/www.ccabogados.com\/wp-content\/uploads\/2022\/10\/Visa-de-Jubilado-740x500.webp\" alt=\"Visa de Jubilado\" \/><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"bottom_box\">\n\t\t\t\t\t\t\t\t<div class=\"bc_content\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"bc_title\"><a target=\"_self\" href=\"https:\/\/www.ccabogados.com\/es\/info\/visa-de-jubilado\/\">Visa de Jubilado<\/a><\/h2>\n\t\t\t\t\t\t\t\t\t<div class=\"featured_items_meta\"><a href=\"https:\/\/www.ccabogados.com\/es\/portcat\/visas\/\">Visas<\/a>\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n                                <div class=\"excerpt\">Comenzamos el proceso en el Servicio Nacional de Migraci\u00f3n. Todo el proceso demora alrededor de seis meses. <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><div class=\"clear\"><\/div><\/div><div class=\"text-center\"><a href=\"javascript:void(0)\" class=\"load_more_works fs_port_loadmore shortcode_button btn_normal btn_type1\">Cargar m\u00e1s<\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Cualquier persona de cualquier pa&iacute;s puede solicitar esta visa en Panam&aacute; Requisitos m&iacute;nimos: Una pensi&oacute;n vitalicia de un m&iacute;nimo de $1,000 al mes. Si viene con su c&oacute;nyuge, la pensi&oacute;n debe ser de $1,250.00. Puede traer a otros familiares, como hijos o padres, y la pensi&oacute;n debe aumentar en $250 por cada persona adicional que traiga. Antecedentes Penales del pa&iacute;s de origen para todos los adultos que soliciten la visa. Certificado de Matrimonio si viene con su c&oacute;nyuge. Certificado de Nacimiento si viene con hijos o el Certificado de Nacimiento del solicitante si viene con sus padres. Hay otros requisitos que se pueden obtener en Panam&aacute;. TODOS LOS DOCUMENTOS provenientes del extranjero deben estar debidamente legalizados a trav&eacute;s del Consulado Paname&ntilde;o en el pa&iacute;s de origen o mediante Apostilla. Beneficios: Obtendr&aacute; una exenci&oacute;n de impuestos de importaci&oacute;n para bienes del hogar. Tendr&aacute; una exenci&oacute;n de impuestos de importaci&oacute;n para traer un auto nuevo cada dos a&ntilde;os. Puede obtener descuentos en servicios como facturas de servicios p&uacute;blicos, boletos de avi&oacute;n, honorarios m&eacute;dicos y tarifas de entrada a cines, eventos culturales y deportivos, entre otros, de la siguiente manera: 25% de descuento en facturas de servicios p&uacute;blicos. 25% de descuento en boletos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-613","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Servicios de visas y residencias en David - Chiriqu\u00ed - Boquete - Santiago de Veraguas - Panam\u00e1<\/title>\n<meta name=\"description\" content=\"En CC Abogados, ofrecemos servicios de visas y residencias en David, Chiriqu\u00ed, Panam\u00e1. Cont\u00e1ctenos sin compromiso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ccabogados.com\/es\/visas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servicios de visas y residencias en David - Chiriqu\u00ed - Boquete - Santiago de Veraguas - Panam\u00e1\" \/>\n<meta property=\"og:description\" content=\"En CC Abogados, ofrecemos servicios de visas y residencias en David, Chiriqu\u00ed, Panam\u00e1. Cont\u00e1ctenos sin compromiso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ccabogados.com\/es\/visas\/\" \/>\n<meta property=\"og:site_name\" content=\"CC Abogados\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T15:32:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ccabogados.com\/es\/visas\/\",\"url\":\"https:\/\/www.ccabogados.com\/es\/visas\/\",\"name\":\"Servicios de visas y residencias en David - Chiriqu\u00ed - Boquete - Santiago de Veraguas - Panam\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/www.ccabogados.com\/#website\"},\"datePublished\":\"2022-10-20T14:15:35+00:00\",\"dateModified\":\"2024-06-11T15:32:11+00:00\",\"description\":\"En CC Abogados, ofrecemos servicios de visas y residencias en David, Chiriqu\u00ed, Panam\u00e1. Cont\u00e1ctenos sin compromiso.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ccabogados.com\/es\/visas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ccabogados.com\/es\/visas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ccabogados.com\/es\/visas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ccabogados.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ccabogados.com\/#website\",\"url\":\"https:\/\/www.ccabogados.com\/\",\"name\":\"CC Abogados\",\"description\":\"Abogados, David, Panam\u00e1\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ccabogados.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servicios de visas y residencias en David - Chiriqu\u00ed - Boquete - Santiago de Veraguas - Panam\u00e1","description":"En CC Abogados, ofrecemos servicios de visas y residencias en David, Chiriqu\u00ed, Panam\u00e1. Cont\u00e1ctenos sin compromiso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ccabogados.com\/es\/visas\/","og_locale":"es_ES","og_type":"article","og_title":"Servicios de visas y residencias en David - Chiriqu\u00ed - Boquete - Santiago de Veraguas - Panam\u00e1","og_description":"En CC Abogados, ofrecemos servicios de visas y residencias en David, Chiriqu\u00ed, Panam\u00e1. Cont\u00e1ctenos sin compromiso.","og_url":"https:\/\/www.ccabogados.com\/es\/visas\/","og_site_name":"CC Abogados","article_modified_time":"2024-06-11T15:32:11+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ccabogados.com\/es\/visas\/","url":"https:\/\/www.ccabogados.com\/es\/visas\/","name":"Servicios de visas y residencias en David - Chiriqu\u00ed - Boquete - Santiago de Veraguas - Panam\u00e1","isPartOf":{"@id":"https:\/\/www.ccabogados.com\/#website"},"datePublished":"2022-10-20T14:15:35+00:00","dateModified":"2024-06-11T15:32:11+00:00","description":"En CC Abogados, ofrecemos servicios de visas y residencias en David, Chiriqu\u00ed, Panam\u00e1. Cont\u00e1ctenos sin compromiso.","breadcrumb":{"@id":"https:\/\/www.ccabogados.com\/es\/visas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ccabogados.com\/es\/visas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ccabogados.com\/es\/visas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccabogados.com\/es\/"},{"@type":"ListItem","position":2,"name":"Visas"}]},{"@type":"WebSite","@id":"https:\/\/www.ccabogados.com\/#website","url":"https:\/\/www.ccabogados.com\/","name":"CC Abogados","description":"Abogados, David, Panam\u00e1","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccabogados.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.ccabogados.com\/es\/wp-json\/wp\/v2\/pages\/613"}],"collection":[{"href":"https:\/\/www.ccabogados.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ccabogados.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccabogados.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccabogados.com\/es\/wp-json\/wp\/v2\/comments?post=613"}],"version-history":[{"count":1,"href":"https:\/\/www.ccabogados.com\/es\/wp-json\/wp\/v2\/pages\/613\/revisions"}],"predecessor-version":[{"id":615,"href":"https:\/\/www.ccabogados.com\/es\/wp-json\/wp\/v2\/pages\/613\/revisions\/615"}],"wp:attachment":[{"href":"https:\/\/www.ccabogados.com\/es\/wp-json\/wp\/v2\/media?parent=613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}